{"id":3592,"date":"2020-12-30T23:38:44","date_gmt":"2020-12-30T22:38:44","guid":{"rendered":"https:\/\/www.edizioniterramarique.com\/?p=3592"},"modified":"2020-12-30T23:38:44","modified_gmt":"2020-12-30T22:38:44","slug":"zero-motivi-per-non-essere-fashion","status":"publish","type":"post","link":"https:\/\/www.edizioniterramarique.com\/en\/zero-motivi-per-non-essere-fashion\/","title":{"rendered":"ZERO MOTIVI PER NON ESSERE FASHION"},"content":{"rendered":"<p>A: \u201cE tu che lavoro fai?\u201d.<br \/>\nB: \u201cIl fashion stylist!\u201d.<br \/>\nA: \u201cAh, quindi disegni abiti?\u201d.<br \/>\nB: \u201cNo, no! Non sono uno stilista\u201d.<br \/>\nB ha lo sguardo perso, ma come sempre schiarisce la voce e si prepara a sciorinare molteplici spiegazioni.<br \/>\nEh s\u00ec, perch\u00e9 questo \u00e8 il dialogo che uno stylist si ritrova spesso a sostenere. Molto spesso.<br \/>\nMa cosa c\u2019\u00e8 di pi\u00f9 bello che aprire il proprio mondo al prossimo illustrando il proprio mestiere, mestiere che \u00e8 sconosciuto a tanti, ma che \u00e8 fondamentale nel mondo della moda?<br \/>\nSe state leggendo questo libro, questo manuale, avete deciso di intraprendere un percorso, lavorativo o meramente chiarificatore.<br \/>\nLa figura dello stylist opera nel fashion system su pi\u00f9 fronti: ha il compito di comprendere il messaggio che si cela dietro la creazione di una collezione, cosa il brand, la persona o l\u2019artista vuole comunicare al mondo e deve rendere il tutto fruibile a chi osserva.<br \/>\nLo fa creando un servizio fotografico, curando la creazione di un look di sfilata o studiando quello pi\u00f9 adatto per una celebrity in un evento. Segue e crea i costumi per una produzione.<br \/>\n\u00c8 un lavoro meraviglioso, stimolante, stancante e che consente di conoscere realt\u00e0 diverse e di mettersi sempre in gioco.<br \/>\nAlla base di tutto devono esserci un grande studio del settore, una smisurata curiosit\u00e0 e una fervida immaginazione. La moda \u00e8 arte e come tale \u00e8 ovunque intorno a noi! Dobbiamo aprire gli occhi, la mente e il cuore e accogliere gli stimoli che riceviamo.<br \/>\nMa tutto questo, senza delle solide fondamenta, non sta in piedi. Uno stylist deve studiare, conoscere tutto quello che ruota attorno a tessuti, forme e colori. Deve seguire le tendenze e anche anticiparle. Deve essere allo stesso tempo un cool hunter, un consulente d\u2019immagine, un sarto e uno psicologo.<br \/>\nState pensando a un supereroe? Ma no, non spaventatevi! \u00c8 un lavoro bello e complesso come tanti altri e come tutti i mestieri richiede delle skills precise.<br \/>\nEmpatia, elasticit\u00e0 ed ecletticismo: sono le tre \u201ce\u201d, le tre parole che meglio riassumono le competenze richieste.<br \/>\nE se adesso vi ho spaventato abbastanza, siete pronti per immergervi in questa lettura che vi guider\u00e0 e vi rasserener\u00e0, perch\u00e9 sia chi vi sta scrivendo ora, sia chi ha ideato e curato la realizzazione di questo manuale ce l\u2019ha fatta! Ed entrambi, dopo anni di esperienze, si divertono ancora tanto ad esercitare questa, non sempre inquadrabile, professione. <\/p>\n<p>                                                                                                                       Paola Percoco<\/p>","protected":false},"excerpt":{"rendered":"<p>A: \u201cE tu che lavoro fai?\u201d. B: \u201cIl fashion stylist!\u201d. A: \u201cAh, quindi disegni abiti?\u201d. B: \u201cNo, no! Non sono uno stilista\u201d. B ha lo sguardo perso, ma come sempre schiarisce la voce e si prepara a sciorinare molteplici spiegazioni. Eh s\u00ec, perch\u00e9 questo \u00e8 il dialogo che uno stylist si ritrova spesso a sostenere. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3590,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-3592","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ZERO MOTIVI PER NON ESSERE FASHION &#8226; Edizioni Terra marique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.edizioniterramarique.com\/en\/zero-motivi-per-non-essere-fashion\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ZERO MOTIVI PER NON ESSERE FASHION &#8226; Edizioni Terra marique\" \/>\n<meta property=\"og:description\" content=\"A: \u201cE tu che lavoro fai?\u201d. B: \u201cIl fashion stylist!\u201d. A: \u201cAh, quindi disegni abiti?\u201d. B: \u201cNo, no! Non sono uno stilista\u201d. B ha lo sguardo perso, ma come sempre schiarisce la voce e si prepara a sciorinare molteplici spiegazioni. Eh s\u00ec, perch\u00e9 questo \u00e8 il dialogo che uno stylist si ritrova spesso a sostenere. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.edizioniterramarique.com\/en\/zero-motivi-per-non-essere-fashion\/\" \/>\n<meta property=\"og:site_name\" content=\"Edizioni Terra marique\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-30T22:38:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.edizioniterramarique.com\/wp-content\/uploads\/2020\/12\/Zero-motivi-per-non-essere-fashion-Copertina-PER-SITO-TM.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"200\" \/>\n\t<meta property=\"og:image:height\" content=\"299\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"terramarique\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"terramarique\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.edizioniterramarique.com\\\/en\\\/zero-motivi-per-non-essere-fashion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.edizioniterramarique.com\\\/en\\\/zero-motivi-per-non-essere-fashion\\\/\"},\"author\":{\"name\":\"terramarique\",\"@id\":\"https:\\\/\\\/www.edizioniterramarique.com\\\/#\\\/schema\\\/person\\\/23151b760764010bb591159120de3824\"},\"headline\":\"ZERO MOTIVI PER NON ESSERE FASHION\",\"datePublished\":\"2020-12-30T22:38:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.edizioniterramarique.com\\\/en\\\/zero-motivi-per-non-essere-fashion\\\/\"},\"wordCount\":404,\"publisher\":{\"@id\":\"https:\\\/\\\/www.edizioniterramarique.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.edizioniterramarique.com\\\/en\\\/zero-motivi-per-non-essere-fashion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.edizioniterramarique.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Zero-motivi-per-non-essere-fashion-Copertina-PER-SITO-TM.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.edizioniterramarique.com\\\/en\\\/zero-motivi-per-non-essere-fashion\\\/\",\"url\":\"https:\\\/\\\/www.edizioniterramarique.com\\\/en\\\/zero-motivi-per-non-essere-fashion\\\/\",\"name\":\"ZERO MOTIVI PER NON ESSERE FASHION &#8226; Edizioni Terra marique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.edizioniterramarique.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.edizioniterramarique.com\\\/en\\\/zero-motivi-per-non-essere-fashion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.edizioniterramarique.com\\\/en\\\/zero-motivi-per-non-essere-fashion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.edizioniterramarique.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Zero-motivi-per-non-essere-fashion-Copertina-PER-SITO-TM.jpg\",\"datePublished\":\"2020-12-30T22:38:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.edizioniterramarique.com\\\/en\\\/zero-motivi-per-non-essere-fashion\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.edizioniterramarique.com\\\/en\\\/zero-motivi-per-non-essere-fashion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.edizioniterramarique.com\\\/en\\\/zero-motivi-per-non-essere-fashion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.edizioniterramarique.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Zero-motivi-per-non-essere-fashion-Copertina-PER-SITO-TM.jpg\",\"contentUrl\":\"https:\\\/\\\/www.edizioniterramarique.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Zero-motivi-per-non-essere-fashion-Copertina-PER-SITO-TM.jpg\",\"width\":200,\"height\":299,\"caption\":\"Copertina Zero motivi per non essere fashion\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.edizioniterramarique.com\\\/en\\\/zero-motivi-per-non-essere-fashion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.edizioniterramarique.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ZERO MOTIVI PER NON ESSERE FASHION\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.edizioniterramarique.com\\\/#website\",\"url\":\"https:\\\/\\\/www.edizioniterramarique.com\\\/\",\"name\":\"Edizioni Terra marique\",\"description\":\"Edizioni Terra marique\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.edizioniterramarique.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.edizioniterramarique.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.edizioniterramarique.com\\\/#organization\",\"name\":\"Edizioni Terra marique\",\"url\":\"https:\\\/\\\/www.edizioniterramarique.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.edizioniterramarique.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.edizioniterramarique.com\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/logo_web1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.edizioniterramarique.com\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/logo_web1.jpg\",\"width\":200,\"height\":109,\"caption\":\"Edizioni Terra marique\"},\"image\":{\"@id\":\"https:\\\/\\\/www.edizioniterramarique.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.edizioniterramarique.com\\\/#\\\/schema\\\/person\\\/23151b760764010bb591159120de3824\",\"name\":\"terramarique\",\"url\":\"https:\\\/\\\/www.edizioniterramarique.com\\\/en\\\/author\\\/terramarique\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ZERO MOTIVI PER NON ESSERE FASHION &#8226; Edizioni Terra marique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.edizioniterramarique.com\/en\/zero-motivi-per-non-essere-fashion\/","og_locale":"en_GB","og_type":"article","og_title":"ZERO MOTIVI PER NON ESSERE FASHION &#8226; Edizioni Terra marique","og_description":"A: \u201cE tu che lavoro fai?\u201d. B: \u201cIl fashion stylist!\u201d. A: \u201cAh, quindi disegni abiti?\u201d. B: \u201cNo, no! Non sono uno stilista\u201d. B ha lo sguardo perso, ma come sempre schiarisce la voce e si prepara a sciorinare molteplici spiegazioni. Eh s\u00ec, perch\u00e9 questo \u00e8 il dialogo che uno stylist si ritrova spesso a sostenere. [&hellip;]","og_url":"https:\/\/www.edizioniterramarique.com\/en\/zero-motivi-per-non-essere-fashion\/","og_site_name":"Edizioni Terra marique","article_published_time":"2020-12-30T22:38:44+00:00","og_image":[{"width":200,"height":299,"url":"https:\/\/www.edizioniterramarique.com\/wp-content\/uploads\/2020\/12\/Zero-motivi-per-non-essere-fashion-Copertina-PER-SITO-TM.jpg","type":"image\/jpeg"}],"author":"terramarique","twitter_misc":{"Written by":"terramarique","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.edizioniterramarique.com\/en\/zero-motivi-per-non-essere-fashion\/#article","isPartOf":{"@id":"https:\/\/www.edizioniterramarique.com\/en\/zero-motivi-per-non-essere-fashion\/"},"author":{"name":"terramarique","@id":"https:\/\/www.edizioniterramarique.com\/#\/schema\/person\/23151b760764010bb591159120de3824"},"headline":"ZERO MOTIVI PER NON ESSERE FASHION","datePublished":"2020-12-30T22:38:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.edizioniterramarique.com\/en\/zero-motivi-per-non-essere-fashion\/"},"wordCount":404,"publisher":{"@id":"https:\/\/www.edizioniterramarique.com\/#organization"},"image":{"@id":"https:\/\/www.edizioniterramarique.com\/en\/zero-motivi-per-non-essere-fashion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.edizioniterramarique.com\/wp-content\/uploads\/2020\/12\/Zero-motivi-per-non-essere-fashion-Copertina-PER-SITO-TM.jpg","articleSection":["News"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.edizioniterramarique.com\/en\/zero-motivi-per-non-essere-fashion\/","url":"https:\/\/www.edizioniterramarique.com\/en\/zero-motivi-per-non-essere-fashion\/","name":"ZERO MOTIVI PER NON ESSERE FASHION &#8226; Edizioni Terra marique","isPartOf":{"@id":"https:\/\/www.edizioniterramarique.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.edizioniterramarique.com\/en\/zero-motivi-per-non-essere-fashion\/#primaryimage"},"image":{"@id":"https:\/\/www.edizioniterramarique.com\/en\/zero-motivi-per-non-essere-fashion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.edizioniterramarique.com\/wp-content\/uploads\/2020\/12\/Zero-motivi-per-non-essere-fashion-Copertina-PER-SITO-TM.jpg","datePublished":"2020-12-30T22:38:44+00:00","breadcrumb":{"@id":"https:\/\/www.edizioniterramarique.com\/en\/zero-motivi-per-non-essere-fashion\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.edizioniterramarique.com\/en\/zero-motivi-per-non-essere-fashion\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.edizioniterramarique.com\/en\/zero-motivi-per-non-essere-fashion\/#primaryimage","url":"https:\/\/www.edizioniterramarique.com\/wp-content\/uploads\/2020\/12\/Zero-motivi-per-non-essere-fashion-Copertina-PER-SITO-TM.jpg","contentUrl":"https:\/\/www.edizioniterramarique.com\/wp-content\/uploads\/2020\/12\/Zero-motivi-per-non-essere-fashion-Copertina-PER-SITO-TM.jpg","width":200,"height":299,"caption":"Copertina Zero motivi per non essere fashion"},{"@type":"BreadcrumbList","@id":"https:\/\/www.edizioniterramarique.com\/en\/zero-motivi-per-non-essere-fashion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.edizioniterramarique.com\/"},{"@type":"ListItem","position":2,"name":"ZERO MOTIVI PER NON ESSERE FASHION"}]},{"@type":"WebSite","@id":"https:\/\/www.edizioniterramarique.com\/#website","url":"https:\/\/www.edizioniterramarique.com\/","name":"Edizioni Terra marique","description":"Edizioni Terra marique","publisher":{"@id":"https:\/\/www.edizioniterramarique.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.edizioniterramarique.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.edizioniterramarique.com\/#organization","name":"Edizioni Terra marique","url":"https:\/\/www.edizioniterramarique.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.edizioniterramarique.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.edizioniterramarique.com\/wp-content\/uploads\/2014\/02\/logo_web1.jpg","contentUrl":"https:\/\/www.edizioniterramarique.com\/wp-content\/uploads\/2014\/02\/logo_web1.jpg","width":200,"height":109,"caption":"Edizioni Terra marique"},"image":{"@id":"https:\/\/www.edizioniterramarique.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.edizioniterramarique.com\/#\/schema\/person\/23151b760764010bb591159120de3824","name":"terramarique","url":"https:\/\/www.edizioniterramarique.com\/en\/author\/terramarique\/"}]}},"_links":{"self":[{"href":"https:\/\/www.edizioniterramarique.com\/en\/wp-json\/wp\/v2\/posts\/3592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.edizioniterramarique.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.edizioniterramarique.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.edizioniterramarique.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.edizioniterramarique.com\/en\/wp-json\/wp\/v2\/comments?post=3592"}],"version-history":[{"count":1,"href":"https:\/\/www.edizioniterramarique.com\/en\/wp-json\/wp\/v2\/posts\/3592\/revisions"}],"predecessor-version":[{"id":3593,"href":"https:\/\/www.edizioniterramarique.com\/en\/wp-json\/wp\/v2\/posts\/3592\/revisions\/3593"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.edizioniterramarique.com\/en\/wp-json\/wp\/v2\/media\/3590"}],"wp:attachment":[{"href":"https:\/\/www.edizioniterramarique.com\/en\/wp-json\/wp\/v2\/media?parent=3592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.edizioniterramarique.com\/en\/wp-json\/wp\/v2\/categories?post=3592"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.edizioniterramarique.com\/en\/wp-json\/wp\/v2\/tags?post=3592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}